{"id":266,"date":"2025-08-21T19:55:13","date_gmt":"2025-08-21T19:55:13","guid":{"rendered":"https:\/\/delicisollc.com\/?post_type=product&#038;p=266"},"modified":"2025-08-21T20:14:45","modified_gmt":"2025-08-21T20:14:45","slug":"sun-kissed-3","status":"publish","type":"product","link":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/","title":{"rendered":"Sun Kissed"},"content":{"rendered":"<p>Body Oil<\/p>","protected":false},"excerpt":{"rendered":"<p>This is a nourishing body butter designed to hydrate, and rejuvenate the skin, leaving it feeling soft and radiant.<\/p>","protected":false},"featured_media":267,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[36,37],"product_tag":[],"class_list":["post-266","product","type-product","status-publish","has-post-thumbnail","product_cat-bath-body-oil","product_cat-body-butter","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sun Kissed - Deliciso, LLC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sun Kissed - Deliciso, LLC\" \/>\n<meta property=\"og:description\" content=\"This is a nourishing body butter designed to hydrate, and rejuvenate the skin, leaving it feeling soft and radiant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Deliciso, LLC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T20:14:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/08\/Sun-Kissed-body-oil.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/delicisollc.com\\\/es\\\/producto\\\/sun-kissed-3\\\/\",\"url\":\"https:\\\/\\\/delicisollc.com\\\/es\\\/producto\\\/sun-kissed-3\\\/\",\"name\":\"Sun Kissed - Deliciso, LLC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delicisollc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/delicisollc.com\\\/es\\\/producto\\\/sun-kissed-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/delicisollc.com\\\/es\\\/producto\\\/sun-kissed-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/delicisollc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Sun-Kissed-body-oil.jpeg\",\"datePublished\":\"2025-08-21T19:55:13+00:00\",\"dateModified\":\"2025-08-21T20:14:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delicisollc.com\\\/es\\\/producto\\\/sun-kissed-3\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/delicisollc.com\\\/es\\\/producto\\\/sun-kissed-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/delicisollc.com\\\/es\\\/producto\\\/sun-kissed-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/delicisollc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Sun-Kissed-body-oil.jpeg\",\"contentUrl\":\"https:\\\/\\\/delicisollc.com\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Sun-Kissed-body-oil.jpeg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delicisollc.com\\\/es\\\/producto\\\/sun-kissed-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/delicisollc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/delicisollc.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sun Kissed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delicisollc.com\\\/#website\",\"url\":\"https:\\\/\\\/delicisollc.com\\\/\",\"name\":\"Deliciso, LLC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delicisollc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sun Kissed - Deliciso, LLC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/","og_locale":"es_MX","og_type":"article","og_title":"Sun Kissed - Deliciso, LLC","og_description":"This is a nourishing body butter designed to hydrate, and rejuvenate the skin, leaving it feeling soft and radiant.","og_url":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/","og_site_name":"Deliciso, LLC","article_modified_time":"2025-08-21T20:14:45+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/08\/Sun-Kissed-body-oil.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/","url":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/","name":"Sun Kissed - Deliciso, LLC","isPartOf":{"@id":"https:\/\/delicisollc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/#primaryimage"},"image":{"@id":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/#primaryimage"},"thumbnailUrl":"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/08\/Sun-Kissed-body-oil.jpeg","datePublished":"2025-08-21T19:55:13+00:00","dateModified":"2025-08-21T20:14:45+00:00","breadcrumb":{"@id":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/#primaryimage","url":"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/08\/Sun-Kissed-body-oil.jpeg","contentUrl":"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/08\/Sun-Kissed-body-oil.jpeg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/delicisollc.com\/es\/producto\/sun-kissed-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/delicisollc.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/delicisollc.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Sun Kissed"}]},{"@type":"WebSite","@id":"https:\/\/delicisollc.com\/#website","url":"https:\/\/delicisollc.com\/","name":"Deliciso, LLC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delicisollc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/comments?post=266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/media\/267"}],"wp:attachment":[{"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/media?parent=266"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product_brand?post=266"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product_cat?post=266"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product_tag?post=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}