{"id":318,"date":"2025-10-23T00:42:48","date_gmt":"2025-10-23T00:42:48","guid":{"rendered":"https:\/\/delicisollc.com\/?post_type=product&#038;p=318"},"modified":"2025-10-23T22:48:39","modified_gmt":"2025-10-23T22:48:39","slug":"butterfly-kisses-bath-salt","status":"publish","type":"product","link":"https:\/\/delicisollc.com\/es\/producto\/butterfly-kisses-bath-salt\/","title":{"rendered":"Butterfly Kisses Bath Salt"},"content":{"rendered":"<p>Melt away the day&#8217;s stresses with a relaxing salt bath<\/p>","protected":false},"excerpt":{"rendered":"<p>Melt away the day&#8217;s stresses with a relaxing salt bath<\/p>","protected":false},"featured_media":319,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_brand":[],"product_cat":[36,38],"product_tag":[],"class_list":["post-318","product","type-product","status-publish","has-post-thumbnail","product_cat-bath-body-oil","product_cat-bath-salts","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Butterfly Kisses Bath Salt - Deliciso, LLC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/delicisollc.com\/es\/producto\/butterfly-kisses-bath-salt\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Butterfly Kisses Bath Salt - Deliciso, LLC\" \/>\n<meta property=\"og:description\" content=\"Melt away the day&#8217;s stresses with a relaxing salt bath\" \/>\n<meta property=\"og:url\" content=\"https:\/\/delicisollc.com\/es\/producto\/butterfly-kisses-bath-salt\/\" \/>\n<meta property=\"og:site_name\" content=\"Deliciso, LLC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-23T22:48:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/10\/Butterfly-Kisses-Salt-Bath-rotated.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/delicisollc.com\\\/product\\\/butterfly-kisses-bath-salt\\\/\",\"url\":\"https:\\\/\\\/delicisollc.com\\\/product\\\/butterfly-kisses-bath-salt\\\/\",\"name\":\"Butterfly Kisses Bath Salt - Deliciso, LLC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/delicisollc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/delicisollc.com\\\/product\\\/butterfly-kisses-bath-salt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/delicisollc.com\\\/product\\\/butterfly-kisses-bath-salt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/delicisollc.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Butterfly-Kisses-Salt-Bath-rotated.jpg\",\"datePublished\":\"2025-10-23T00:42:48+00:00\",\"dateModified\":\"2025-10-23T22:48:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/delicisollc.com\\\/product\\\/butterfly-kisses-bath-salt\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/delicisollc.com\\\/product\\\/butterfly-kisses-bath-salt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/delicisollc.com\\\/product\\\/butterfly-kisses-bath-salt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/delicisollc.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Butterfly-Kisses-Salt-Bath-rotated.jpg\",\"contentUrl\":\"https:\\\/\\\/delicisollc.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Butterfly-Kisses-Salt-Bath-rotated.jpg\",\"width\":240,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/delicisollc.com\\\/product\\\/butterfly-kisses-bath-salt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/delicisollc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/delicisollc.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Butterfly Kisses Bath Salt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/delicisollc.com\\\/#website\",\"url\":\"https:\\\/\\\/delicisollc.com\\\/\",\"name\":\"Deliciso, LLC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/delicisollc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Butterfly Kisses Bath Salt - Deliciso, LLC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/delicisollc.com\/es\/producto\/butterfly-kisses-bath-salt\/","og_locale":"es_MX","og_type":"article","og_title":"Butterfly Kisses Bath Salt - Deliciso, LLC","og_description":"Melt away the day&#8217;s stresses with a relaxing salt bath","og_url":"https:\/\/delicisollc.com\/es\/producto\/butterfly-kisses-bath-salt\/","og_site_name":"Deliciso, LLC","article_modified_time":"2025-10-23T22:48:39+00:00","og_image":[{"width":240,"height":320,"url":"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/10\/Butterfly-Kisses-Salt-Bath-rotated.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/delicisollc.com\/product\/butterfly-kisses-bath-salt\/","url":"https:\/\/delicisollc.com\/product\/butterfly-kisses-bath-salt\/","name":"Butterfly Kisses Bath Salt - Deliciso, LLC","isPartOf":{"@id":"https:\/\/delicisollc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/delicisollc.com\/product\/butterfly-kisses-bath-salt\/#primaryimage"},"image":{"@id":"https:\/\/delicisollc.com\/product\/butterfly-kisses-bath-salt\/#primaryimage"},"thumbnailUrl":"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/10\/Butterfly-Kisses-Salt-Bath-rotated.jpg","datePublished":"2025-10-23T00:42:48+00:00","dateModified":"2025-10-23T22:48:39+00:00","breadcrumb":{"@id":"https:\/\/delicisollc.com\/product\/butterfly-kisses-bath-salt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/delicisollc.com\/product\/butterfly-kisses-bath-salt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/delicisollc.com\/product\/butterfly-kisses-bath-salt\/#primaryimage","url":"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/10\/Butterfly-Kisses-Salt-Bath-rotated.jpg","contentUrl":"https:\/\/delicisollc.com\/wp-content\/uploads\/2025\/10\/Butterfly-Kisses-Salt-Bath-rotated.jpg","width":240,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/delicisollc.com\/product\/butterfly-kisses-bath-salt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/delicisollc.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/delicisollc.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Butterfly Kisses Bath Salt"}]},{"@type":"WebSite","@id":"https:\/\/delicisollc.com\/#website","url":"https:\/\/delicisollc.com\/","name":"Deliciso, LLC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/delicisollc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/comments?post=318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/media\/319"}],"wp:attachment":[{"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product_brand?post=318"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product_cat?post=318"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/delicisollc.com\/es\/wp-json\/wp\/v2\/product_tag?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}